{"id":134,"date":"2024-09-13T12:42:08","date_gmt":"2024-09-13T10:42:08","guid":{"rendered":"https:\/\/mustpalma.com\/?post_type=portfolio&#038;p=134"},"modified":"2025-10-19T10:49:39","modified_gmt":"2025-10-19T08:49:39","slug":"catalina-calafat","status":"publish","type":"portfolio","link":"https:\/\/mustpalma.com\/ca\/portfolio-item\/catalina-calafat\/","title":{"rendered":"Catalina Calafat"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":371,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":""},"portfolio-types":[13,11],"class_list":["post-134","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-psicologia-adultos","portfolio-types-psicologia-general-sanitaria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Catalina Calafat - Mustpalma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mustpalma.com\/ca\/portfolio-item\/catalina-calafat\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catalina Calafat - Mustpalma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mustpalma.com\/ca\/portfolio-item\/catalina-calafat\/\" \/>\n<meta property=\"og:site_name\" content=\"Mustpalma\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-19T08:49:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mustpalma.com\\\/portfolio-item\\\/catalina-calafat\\\/\",\"url\":\"https:\\\/\\\/mustpalma.com\\\/portfolio-item\\\/catalina-calafat\\\/\",\"name\":\"Catalina Calafat - Mustpalma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mustpalma.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mustpalma.com\\\/portfolio-item\\\/catalina-calafat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mustpalma.com\\\/portfolio-item\\\/catalina-calafat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mustpalma.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png\",\"datePublished\":\"2024-09-13T10:42:08+00:00\",\"dateModified\":\"2025-10-19T08:49:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mustpalma.com\\\/portfolio-item\\\/catalina-calafat\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mustpalma.com\\\/portfolio-item\\\/catalina-calafat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/mustpalma.com\\\/portfolio-item\\\/catalina-calafat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mustpalma.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png\",\"contentUrl\":\"https:\\\/\\\/mustpalma.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png\",\"width\":250,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mustpalma.com\\\/portfolio-item\\\/catalina-calafat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mustpalma.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalina Calafat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mustpalma.com\\\/#website\",\"url\":\"https:\\\/\\\/mustpalma.com\\\/\",\"name\":\"Psic\u00f3logos en Mallorca: Servicios de Psicolog\u00eda para Mejorar Tu Bienestar\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mustpalma.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mustpalma.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mustpalma.com\\\/#organization\",\"name\":\"Psic\u00f3logos en Mallorca: Servicios de Psicolog\u00eda para Mejorar Tu Bienestar\",\"url\":\"https:\\\/\\\/mustpalma.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/mustpalma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mustpalma.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-Version-reducida-con-tagline-circular-color.png\",\"contentUrl\":\"https:\\\/\\\/mustpalma.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-Version-reducida-con-tagline-circular-color.png\",\"width\":512,\"height\":512,\"caption\":\"Psic\u00f3logos en Mallorca: Servicios de Psicolog\u00eda para Mejorar Tu Bienestar\"},\"image\":{\"@id\":\"https:\\\/\\\/mustpalma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/mustpalma\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catalina Calafat - Mustpalma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mustpalma.com\/ca\/portfolio-item\/catalina-calafat\/","og_locale":"ca_ES","og_type":"article","og_title":"Catalina Calafat - Mustpalma","og_url":"https:\/\/mustpalma.com\/ca\/portfolio-item\/catalina-calafat\/","og_site_name":"Mustpalma","article_modified_time":"2025-10-19T08:49:39+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mustpalma.com\/portfolio-item\/catalina-calafat\/","url":"https:\/\/mustpalma.com\/portfolio-item\/catalina-calafat\/","name":"Catalina Calafat - Mustpalma","isPartOf":{"@id":"https:\/\/mustpalma.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mustpalma.com\/portfolio-item\/catalina-calafat\/#primaryimage"},"image":{"@id":"https:\/\/mustpalma.com\/portfolio-item\/catalina-calafat\/#primaryimage"},"thumbnailUrl":"https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png","datePublished":"2024-09-13T10:42:08+00:00","dateModified":"2025-10-19T08:49:39+00:00","breadcrumb":{"@id":"https:\/\/mustpalma.com\/portfolio-item\/catalina-calafat\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mustpalma.com\/portfolio-item\/catalina-calafat\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/mustpalma.com\/portfolio-item\/catalina-calafat\/#primaryimage","url":"https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png","contentUrl":"https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png","width":250,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/mustpalma.com\/portfolio-item\/catalina-calafat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mustpalma.com\/"},{"@type":"ListItem","position":2,"name":"Catalina Calafat"}]},{"@type":"WebSite","@id":"https:\/\/mustpalma.com\/#website","url":"https:\/\/mustpalma.com\/","name":"Psic\u00f3logos en Mallorca: Servicios de Psicolog\u00eda para Mejorar Tu Bienestar","description":"","publisher":{"@id":"https:\/\/mustpalma.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mustpalma.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/mustpalma.com\/#organization","name":"Psic\u00f3logos en Mallorca: Servicios de Psicolog\u00eda para Mejorar Tu Bienestar","url":"https:\/\/mustpalma.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/mustpalma.com\/#\/schema\/logo\/image\/","url":"https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/cropped-Version-reducida-con-tagline-circular-color.png","contentUrl":"https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/cropped-Version-reducida-con-tagline-circular-color.png","width":512,"height":512,"caption":"Psic\u00f3logos en Mallorca: Servicios de Psicolog\u00eda para Mejorar Tu Bienestar"},"image":{"@id":"https:\/\/mustpalma.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/mustpalma\/"]}]}},"uagb_featured_image_src":{"full":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"thumbnail":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"medium":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"medium_large":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"large":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"1536x1536":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"2048x2048":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"trp-custom-language-flag":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1-12x12.png",12,12,true],"be_thumbnail":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1-150x150.png",150,150,true],"be_clients":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1-75x75.png",75,75,true],"slider-content":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"portfolio-mf":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"portfolio-mf-w":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"portfolio-mf-t":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"portfolio-list":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"blog-portfolio":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"blog-single":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false],"mobile-srcset":["https:\/\/mustpalma.com\/wp-content\/uploads\/2024\/09\/catalina-calafat-psicologa-licenciada-palma-de-mallorca-must-1.png",250,250,false]},"uagb_author_info":{"display_name":"MustPAmsALdemO","author_link":"https:\/\/mustpalma.com\/ca\/author\/mustpamsaldemo\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/mustpalma.com\/ca\/wp-json\/wp\/v2\/portfolio\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mustpalma.com\/ca\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/mustpalma.com\/ca\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/mustpalma.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mustpalma.com\/ca\/wp-json\/wp\/v2\/comments?post=134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mustpalma.com\/ca\/wp-json\/wp\/v2\/media\/371"}],"wp:attachment":[{"href":"https:\/\/mustpalma.com\/ca\/wp-json\/wp\/v2\/media?parent=134"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/mustpalma.com\/ca\/wp-json\/wp\/v2\/portfolio-types?post=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}